{"id":13,"date":"2015-12-22T18:02:10","date_gmt":"2015-12-22T18:02:10","guid":{"rendered":"http:\/\/sporchernest-hotel.de\/?page_id=13"},"modified":"2024-01-19T10:59:43","modified_gmt":"2024-01-19T10:59:43","slug":"galerie","status":"publish","type":"page","link":"https:\/\/sporchernest-hotel.de\/de\/galerie","title":{"rendered":"Galerie"},"content":{"rendered":"<h1>Galerie<\/h1>\n<p>&nbsp;<\/p>\n<h2> Ein kleiner Rundgang durchs Sporcher Nest&#8230;<\/h2>\n<p>&nbsp;<br \/>\n\n\t\t<!-- MasterSlider -->\n\t\t<div id=\"P_MS6a97e938c18c6\" class=\"master-slider-parent msl ms-parent-id-3\" style=\"max-width:960px;\">\n\n\t\t\t\n\t\t\t<!-- MasterSlider Main -->\n\t\t\t<div id=\"MS6a97e938c18c6\" class=\"master-slider ms-skin-default\" >\n\t\t\t\t \t\t\t\t \n\t\t\t\t<div  class=\"ms-slide\" data-delay=\"3\" data-fill-mode=\"fill\"  >\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/sporchernest-hotel.de\/wp-content\/plugins\/master-slider\/public\/assets\/css\/blank.gif\" alt=\"\" title=\"\" data-src=\"https:\/\/sporchernest-hotel.de\/wp-content\/uploads\/2016\/07\/Gartenansicht-Tag-Hotel-F\u00fcrth.jpg\" \/>\n\n\n\t<img decoding=\"async\" class=\"ms-thumb\" src=\"https:\/\/sporchernest-hotel.de\/wp-content\/uploads\/2016\/07\/Gartenansicht-Tag-Hotel-F\u00fcrth-128x95.jpg\" alt=\"\" \/>\n\t<div class=\"ms-thumb\" ><div class=\"ms-tab-context\"><div class=\"&quot;ms-tab-context&quot;\"><\/div><\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div  class=\"ms-slide\" data-delay=\"3\" data-fill-mode=\"fill\"  >\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/sporchernest-hotel.de\/wp-content\/plugins\/master-slider\/public\/assets\/css\/blank.gif\" alt=\"\" title=\"\" data-src=\"https:\/\/sporchernest-hotel.de\/wp-content\/uploads\/2016\/07\/Biergarten-Cadolzburg-Sporcher-Nest.jpg\" \/>\n\n\n\t<img decoding=\"async\" class=\"ms-thumb\" src=\"https:\/\/sporchernest-hotel.de\/wp-content\/uploads\/2016\/07\/Biergarten-Cadolzburg-Sporcher-Nest-128x95.jpg\" alt=\"\" \/>\n\t<div class=\"ms-thumb\" ><div class=\"ms-tab-context\"><div class=\"&quot;ms-tab-context&quot;\"><\/div><\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div  class=\"ms-slide\" data-delay=\"3\" data-fill-mode=\"fill\"  >\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/sporchernest-hotel.de\/wp-content\/plugins\/master-slider\/public\/assets\/css\/blank.gif\" alt=\"\" title=\"\" data-src=\"https:\/\/sporchernest-hotel.de\/wp-content\/uploads\/2022\/06\/Eingang2022-galerie.jpg\" \/>\n\n\n\t<img decoding=\"async\" class=\"ms-thumb\" src=\"https:\/\/sporchernest-hotel.de\/wp-content\/uploads\/2022\/06\/Eingang2022-galerie-128x95.jpg\" alt=\"\" \/>\n\t<div class=\"ms-thumb\" ><div class=\"ms-tab-context\"><div class=\"&quot;ms-tab-context&quot;\"><\/div><\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div  class=\"ms-slide\" data-delay=\"3\" data-fill-mode=\"fill\"  >\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/sporchernest-hotel.de\/wp-content\/plugins\/master-slider\/public\/assets\/css\/blank.gif\" alt=\"\" title=\"\" data-src=\"https:\/\/sporchernest-hotel.de\/wp-content\/uploads\/2020\/06\/HOT_02-960.jpg\" \/>\n\n\n\t<img decoding=\"async\" class=\"ms-thumb\" src=\"https:\/\/sporchernest-hotel.de\/wp-content\/uploads\/2020\/06\/HOT_02-960-128x95.jpg\" alt=\"\" \/>\n\t<div class=\"ms-thumb\" ><div class=\"ms-tab-context\"><div class=\"&quot;ms-tab-context&quot;\"><\/div><\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div  class=\"ms-slide\" data-delay=\"3\" data-fill-mode=\"fill\"  >\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/sporchernest-hotel.de\/wp-content\/plugins\/master-slider\/public\/assets\/css\/blank.gif\" alt=\"\" title=\"\" data-src=\"https:\/\/sporchernest-hotel.de\/wp-content\/uploads\/2020\/06\/HOT_03-960.jpg\" \/>\n\n\n\t<img decoding=\"async\" class=\"ms-thumb\" src=\"https:\/\/sporchernest-hotel.de\/wp-content\/uploads\/2020\/06\/HOT_03-960-128x95.jpg\" alt=\"\" \/>\n\t<div class=\"ms-thumb\" ><div class=\"ms-tab-context\"><div class=\"&quot;ms-tab-context&quot;\"><\/div><\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div  class=\"ms-slide\" data-delay=\"3\" data-fill-mode=\"fill\"  >\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/sporchernest-hotel.de\/wp-content\/plugins\/master-slider\/public\/assets\/css\/blank.gif\" alt=\"\" title=\"\" data-src=\"https:\/\/sporchernest-hotel.de\/wp-content\/uploads\/2019\/01\/G5-neu.jpg\" \/>\n\n\n\t<img decoding=\"async\" class=\"ms-thumb\" src=\"https:\/\/sporchernest-hotel.de\/wp-content\/uploads\/2019\/01\/G5-neu-128x95.jpg\" alt=\"\" \/>\n\t<div class=\"ms-thumb\" ><div class=\"ms-tab-context\"><div class=\"&quot;ms-tab-context&quot;\"><\/div><\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div  class=\"ms-slide\" data-delay=\"3\" data-fill-mode=\"fill\"  >\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/sporchernest-hotel.de\/wp-content\/plugins\/master-slider\/public\/assets\/css\/blank.gif\" alt=\"\" title=\"\" data-src=\"https:\/\/sporchernest-hotel.de\/wp-content\/uploads\/2019\/01\/G6.jpg\" \/>\n\n\n\t<img decoding=\"async\" class=\"ms-thumb\" src=\"https:\/\/sporchernest-hotel.de\/wp-content\/uploads\/2019\/01\/G6-128x95.jpg\" alt=\"\" \/>\n\t<div class=\"ms-thumb\" ><div class=\"ms-tab-context\"><div class=\"&quot;ms-tab-context&quot;\"><\/div><\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div  class=\"ms-slide\" data-delay=\"3\" data-fill-mode=\"fill\"  >\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/sporchernest-hotel.de\/wp-content\/plugins\/master-slider\/public\/assets\/css\/blank.gif\" alt=\"\" title=\"\" data-src=\"https:\/\/sporchernest-hotel.de\/wp-content\/uploads\/2019\/01\/G1.jpg\" \/>\n\n\n\t<img decoding=\"async\" class=\"ms-thumb\" src=\"https:\/\/sporchernest-hotel.de\/wp-content\/uploads\/2019\/01\/G1-128x95.jpg\" alt=\"\" \/>\n\t<div class=\"ms-thumb\" ><div class=\"ms-tab-context\"><div class=\"&quot;ms-tab-context&quot;\"><\/div><\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div  class=\"ms-slide\" data-delay=\"3\" data-fill-mode=\"fill\"  >\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/sporchernest-hotel.de\/wp-content\/plugins\/master-slider\/public\/assets\/css\/blank.gif\" alt=\"\" title=\"\" data-src=\"https:\/\/sporchernest-hotel.de\/wp-content\/uploads\/2020\/06\/HOT_04-2020.jpg\" \/>\n\n\n\t<img decoding=\"async\" class=\"ms-thumb\" src=\"https:\/\/sporchernest-hotel.de\/wp-content\/uploads\/2020\/06\/HOT_04-2020-128x95.jpg\" alt=\"\" \/>\n\t<div class=\"ms-thumb\" ><div class=\"ms-tab-context\"><div class=\"&quot;ms-tab-context&quot;\"><\/div><\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div  class=\"ms-slide\" data-delay=\"3\" data-fill-mode=\"fill\"  >\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/sporchernest-hotel.de\/wp-content\/plugins\/master-slider\/public\/assets\/css\/blank.gif\" alt=\"\" title=\"\" data-src=\"https:\/\/sporchernest-hotel.de\/wp-content\/uploads\/2020\/06\/HOT_05-2020.jpg\" \/>\n\n\n\t<img decoding=\"async\" class=\"ms-thumb\" src=\"https:\/\/sporchernest-hotel.de\/wp-content\/uploads\/2020\/06\/HOT_05-2020-128x95.jpg\" alt=\"\" \/>\n\t<div class=\"ms-thumb\" ><div class=\"ms-tab-context\"><div class=\"&quot;ms-tab-context&quot;\"><\/div><\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div  class=\"ms-slide\" data-delay=\"3\" data-fill-mode=\"fill\"  >\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/sporchernest-hotel.de\/wp-content\/plugins\/master-slider\/public\/assets\/css\/blank.gif\" alt=\"\" title=\"\" data-src=\"https:\/\/sporchernest-hotel.de\/wp-content\/uploads\/2019\/02\/TreppeinGalerie.jpg\" \/>\n\n\n\t<img decoding=\"async\" class=\"ms-thumb\" src=\"https:\/\/sporchernest-hotel.de\/wp-content\/uploads\/2019\/02\/TreppeinGalerie-128x95.jpg\" alt=\"\" \/>\n\t<div class=\"ms-thumb\" ><div class=\"ms-tab-context\"><div class=\"&quot;ms-tab-context&quot;\"><\/div><\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div  class=\"ms-slide\" data-delay=\"3\" data-fill-mode=\"fill\"  >\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/sporchernest-hotel.de\/wp-content\/plugins\/master-slider\/public\/assets\/css\/blank.gif\" alt=\"\" title=\"\" data-src=\"https:\/\/sporchernest-hotel.de\/wp-content\/uploads\/2019\/01\/G12-2.jpg\" \/>\n\n\n\t<img decoding=\"async\" class=\"ms-thumb\" src=\"https:\/\/sporchernest-hotel.de\/wp-content\/uploads\/2019\/01\/G12-2-128x95.jpg\" alt=\"\" \/>\n\t<div class=\"ms-thumb\" ><div class=\"ms-tab-context\"><div class=\"&quot;ms-tab-context&quot;\"><\/div><\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div  class=\"ms-slide\" data-delay=\"3\" data-fill-mode=\"fill\"  >\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/sporchernest-hotel.de\/wp-content\/plugins\/master-slider\/public\/assets\/css\/blank.gif\" alt=\"\" title=\"\" data-src=\"https:\/\/sporchernest-hotel.de\/wp-content\/uploads\/2019\/01\/G11-1-neu.jpg\" \/>\n\n\n\t<img decoding=\"async\" class=\"ms-thumb\" src=\"https:\/\/sporchernest-hotel.de\/wp-content\/uploads\/2019\/01\/G11-1-neu-128x95.jpg\" alt=\"\" \/>\n\t<div class=\"ms-thumb\" ><div class=\"ms-tab-context\"><div class=\"&quot;ms-tab-context&quot;\"><\/div><\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div  class=\"ms-slide\" data-delay=\"3\" data-fill-mode=\"fill\"  >\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/sporchernest-hotel.de\/wp-content\/plugins\/master-slider\/public\/assets\/css\/blank.gif\" alt=\"\" title=\"\" data-src=\"https:\/\/sporchernest-hotel.de\/wp-content\/uploads\/2019\/01\/G11-4-neu.jpg\" \/>\n\n\n\t<img decoding=\"async\" class=\"ms-thumb\" src=\"https:\/\/sporchernest-hotel.de\/wp-content\/uploads\/2019\/01\/G11-4-neu-128x95.jpg\" alt=\"\" \/>\n\t<div class=\"ms-thumb\" ><div class=\"ms-tab-context\"><div class=\"&quot;ms-tab-context&quot;\"><\/div><\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div  class=\"ms-slide\" data-delay=\"3\" data-fill-mode=\"fill\"  >\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/sporchernest-hotel.de\/wp-content\/plugins\/master-slider\/public\/assets\/css\/blank.gif\" alt=\"\" title=\"\" data-src=\"https:\/\/sporchernest-hotel.de\/wp-content\/uploads\/2020\/06\/HOT_06-2020.jpg\" \/>\n\n\n\t<img decoding=\"async\" class=\"ms-thumb\" src=\"https:\/\/sporchernest-hotel.de\/wp-content\/uploads\/2020\/06\/HOT_06-2020-128x95.jpg\" alt=\"\" \/>\n\t<div class=\"ms-thumb\" ><div class=\"ms-tab-context\"><div class=\"&quot;ms-tab-context&quot;\"><\/div><\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div  class=\"ms-slide\" data-delay=\"3\" data-fill-mode=\"fill\"  >\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/sporchernest-hotel.de\/wp-content\/plugins\/master-slider\/public\/assets\/css\/blank.gif\" alt=\"\" title=\"\" data-src=\"https:\/\/sporchernest-hotel.de\/wp-content\/uploads\/2019\/01\/G11-8.-neu.jpg\" \/>\n\n\n\t<img decoding=\"async\" class=\"ms-thumb\" src=\"https:\/\/sporchernest-hotel.de\/wp-content\/uploads\/2019\/01\/G11-8.-neu-128x95.jpg\" alt=\"\" \/>\n\t<div class=\"ms-thumb\" ><div class=\"ms-tab-context\"><div class=\"&quot;ms-tab-context&quot;\"><\/div><\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div  class=\"ms-slide\" data-delay=\"3\" data-fill-mode=\"fill\"  >\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/sporchernest-hotel.de\/wp-content\/plugins\/master-slider\/public\/assets\/css\/blank.gif\" alt=\"\" title=\"\" data-src=\"https:\/\/sporchernest-hotel.de\/wp-content\/uploads\/2019\/01\/G11-9.jpg\" \/>\n\n\n\t<img decoding=\"async\" class=\"ms-thumb\" src=\"https:\/\/sporchernest-hotel.de\/wp-content\/uploads\/2019\/01\/G11-9-128x95.jpg\" alt=\"\" \/>\n\t<div class=\"ms-thumb\" ><div class=\"ms-tab-context\"><div class=\"&quot;ms-tab-context&quot;\"><\/div><\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div  class=\"ms-slide\" data-delay=\"3\" data-fill-mode=\"fill\"  >\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/sporchernest-hotel.de\/wp-content\/plugins\/master-slider\/public\/assets\/css\/blank.gif\" alt=\"\" title=\"\" data-src=\"https:\/\/sporchernest-hotel.de\/wp-content\/uploads\/2019\/01\/G11-7-neu.jpg\" \/>\n\n\n\t<img decoding=\"async\" class=\"ms-thumb\" src=\"https:\/\/sporchernest-hotel.de\/wp-content\/uploads\/2019\/01\/G11-7-neu-128x95.jpg\" alt=\"\" \/>\n\t<div class=\"ms-thumb\" ><div class=\"ms-tab-context\"><div class=\"&quot;ms-tab-context&quot;\"><\/div><\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div  class=\"ms-slide\" data-delay=\"3\" data-fill-mode=\"fill\"  >\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/sporchernest-hotel.de\/wp-content\/plugins\/master-slider\/public\/assets\/css\/blank.gif\" alt=\"\" title=\"\" data-src=\"https:\/\/sporchernest-hotel.de\/wp-content\/uploads\/2019\/01\/G11-6-neu.jpg\" \/>\n\n\n\t<img decoding=\"async\" class=\"ms-thumb\" src=\"https:\/\/sporchernest-hotel.de\/wp-content\/uploads\/2019\/01\/G11-6-neu-128x95.jpg\" alt=\"\" \/>\n\t<div class=\"ms-thumb\" ><div class=\"ms-tab-context\"><div class=\"&quot;ms-tab-context&quot;\"><\/div><\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div  class=\"ms-slide\" data-delay=\"3\" data-fill-mode=\"fill\"  >\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/sporchernest-hotel.de\/wp-content\/plugins\/master-slider\/public\/assets\/css\/blank.gif\" alt=\"\" title=\"\" data-src=\"https:\/\/sporchernest-hotel.de\/wp-content\/uploads\/2016\/03\/Badspiegel.jpg\" \/>\n\n\n\t<img decoding=\"async\" class=\"ms-thumb\" src=\"https:\/\/sporchernest-hotel.de\/wp-content\/uploads\/2016\/03\/Badspiegel-128x95.jpg\" alt=\"\" \/>\n\t<div class=\"ms-thumb\" ><div class=\"ms-tab-context\"><div class=\"&quot;ms-tab-context&quot;\"><\/div><\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div  class=\"ms-slide\" data-delay=\"3\" data-fill-mode=\"fill\"  >\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/sporchernest-hotel.de\/wp-content\/plugins\/master-slider\/public\/assets\/css\/blank.gif\" alt=\"\" title=\"\" data-src=\"https:\/\/sporchernest-hotel.de\/wp-content\/uploads\/2019\/01\/Zimmer-3.jpg\" \/>\n\n\n\t<img decoding=\"async\" class=\"ms-thumb\" src=\"https:\/\/sporchernest-hotel.de\/wp-content\/uploads\/2019\/01\/Zimmer-3-128x95.jpg\" alt=\"\" \/>\n\t<div class=\"ms-thumb\" ><div class=\"ms-tab-context\"><div class=\"&quot;ms-tab-context&quot;\"><\/div><\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div  class=\"ms-slide\" data-delay=\"3\" data-fill-mode=\"fill\"  >\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/sporchernest-hotel.de\/wp-content\/plugins\/master-slider\/public\/assets\/css\/blank.gif\" alt=\"\" title=\"\" data-src=\"https:\/\/sporchernest-hotel.de\/wp-content\/uploads\/2019\/01\/Zimmer-7.jpg\" \/>\n\n\n\t<img decoding=\"async\" class=\"ms-thumb\" src=\"https:\/\/sporchernest-hotel.de\/wp-content\/uploads\/2019\/01\/Zimmer-7-128x95.jpg\" alt=\"\" \/>\n\t<div class=\"ms-thumb\" ><div class=\"ms-tab-context\"><div class=\"&quot;ms-tab-context&quot;\"><\/div><\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div  class=\"ms-slide\" data-delay=\"3\" data-fill-mode=\"fill\"  >\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/sporchernest-hotel.de\/wp-content\/plugins\/master-slider\/public\/assets\/css\/blank.gif\" alt=\"\" title=\"\" data-src=\"https:\/\/sporchernest-hotel.de\/wp-content\/uploads\/2019\/01\/Zimmer-9.jpg\" \/>\n\n\n\t<img decoding=\"async\" class=\"ms-thumb\" src=\"https:\/\/sporchernest-hotel.de\/wp-content\/uploads\/2019\/01\/Zimmer-9-128x95.jpg\" alt=\"\" \/>\n\t<div class=\"ms-thumb\" ><div class=\"ms-tab-context\"><div class=\"&quot;ms-tab-context&quot;\"><\/div><\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div  class=\"ms-slide\" data-delay=\"3\" data-fill-mode=\"fill\"  >\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/sporchernest-hotel.de\/wp-content\/plugins\/master-slider\/public\/assets\/css\/blank.gif\" alt=\"\" title=\"\" data-src=\"https:\/\/sporchernest-hotel.de\/wp-content\/uploads\/2019\/01\/Bild-Bademantel.jpg\" \/>\n\n\n\t<img decoding=\"async\" class=\"ms-thumb\" src=\"https:\/\/sporchernest-hotel.de\/wp-content\/uploads\/2019\/01\/Bild-Bademantel-128x95.jpg\" alt=\"\" \/>\n\t<div class=\"ms-thumb\" ><div class=\"ms-tab-context\"><div class=\"&quot;ms-tab-context&quot;\"><\/div><\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div  class=\"ms-slide\" data-delay=\"3\" data-fill-mode=\"fill\"  >\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/sporchernest-hotel.de\/wp-content\/plugins\/master-slider\/public\/assets\/css\/blank.gif\" alt=\"\" title=\"\" data-src=\"https:\/\/sporchernest-hotel.de\/wp-content\/uploads\/2019\/01\/Zimmer-14.jpg\" \/>\n\n\n\t<img decoding=\"async\" class=\"ms-thumb\" src=\"https:\/\/sporchernest-hotel.de\/wp-content\/uploads\/2019\/01\/Zimmer-14-128x95.jpg\" alt=\"\" \/>\n\t<div class=\"ms-thumb\" ><div class=\"ms-tab-context\"><div class=\"&quot;ms-tab-context&quot;\"><\/div><\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div  class=\"ms-slide\" data-delay=\"3\" data-fill-mode=\"fill\"  >\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/sporchernest-hotel.de\/wp-content\/plugins\/master-slider\/public\/assets\/css\/blank.gif\" alt=\"\" title=\"\" data-src=\"https:\/\/sporchernest-hotel.de\/wp-content\/uploads\/2019\/01\/Zimmer-27.jpg\" \/>\n\n\n\t<img decoding=\"async\" class=\"ms-thumb\" src=\"https:\/\/sporchernest-hotel.de\/wp-content\/uploads\/2019\/01\/Zimmer-27-128x95.jpg\" alt=\"\" \/>\n\t<div class=\"ms-thumb\" ><div class=\"ms-tab-context\"><div class=\"&quot;ms-tab-context&quot;\"><\/div><\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div  class=\"ms-slide\" data-delay=\"3\" data-fill-mode=\"fill\"  >\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/sporchernest-hotel.de\/wp-content\/plugins\/master-slider\/public\/assets\/css\/blank.gif\" alt=\"\" title=\"\" data-src=\"https:\/\/sporchernest-hotel.de\/wp-content\/uploads\/2019\/01\/Zimmer-11.jpg\" \/>\n\n\n\t<img decoding=\"async\" class=\"ms-thumb\" src=\"https:\/\/sporchernest-hotel.de\/wp-content\/uploads\/2019\/01\/Zimmer-11-128x95.jpg\" alt=\"\" \/>\n\t<div class=\"ms-thumb\" ><div class=\"ms-tab-context\"><div class=\"&quot;ms-tab-context&quot;\"><\/div><\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div  class=\"ms-slide\" data-delay=\"3\" data-fill-mode=\"fill\"  >\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/sporchernest-hotel.de\/wp-content\/plugins\/master-slider\/public\/assets\/css\/blank.gif\" alt=\"\" title=\"\" data-src=\"https:\/\/sporchernest-hotel.de\/wp-content\/uploads\/2019\/01\/Zimmer-12.jpg\" \/>\n\n\n\t<img decoding=\"async\" class=\"ms-thumb\" src=\"https:\/\/sporchernest-hotel.de\/wp-content\/uploads\/2019\/01\/Zimmer-12-128x95.jpg\" alt=\"\" \/>\n\t<div class=\"ms-thumb\" ><div class=\"ms-tab-context\"><div class=\"&quot;ms-tab-context&quot;\"><\/div><\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div  class=\"ms-slide\" data-delay=\"3\" data-fill-mode=\"fill\"  >\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/sporchernest-hotel.de\/wp-content\/plugins\/master-slider\/public\/assets\/css\/blank.gif\" alt=\"\" title=\"\" data-src=\"https:\/\/sporchernest-hotel.de\/wp-content\/uploads\/2019\/01\/Zimmer-15.jpg\" \/>\n\n\n\t<img decoding=\"async\" class=\"ms-thumb\" src=\"https:\/\/sporchernest-hotel.de\/wp-content\/uploads\/2019\/01\/Zimmer-15-128x95.jpg\" alt=\"\" \/>\n\t<div class=\"ms-thumb\" ><div class=\"ms-tab-context\"><div class=\"&quot;ms-tab-context&quot;\"><\/div><\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div  class=\"ms-slide\" data-delay=\"3\" data-fill-mode=\"fill\"  >\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/sporchernest-hotel.de\/wp-content\/plugins\/master-slider\/public\/assets\/css\/blank.gif\" alt=\"\" title=\"\" data-src=\"https:\/\/sporchernest-hotel.de\/wp-content\/uploads\/2019\/01\/Zimmer-26.jpg\" \/>\n\n\n\t<img decoding=\"async\" class=\"ms-thumb\" src=\"https:\/\/sporchernest-hotel.de\/wp-content\/uploads\/2019\/01\/Zimmer-26-128x95.jpg\" alt=\"\" \/>\n\t<div class=\"ms-thumb\" ><div class=\"ms-tab-context\"><div class=\"&quot;ms-tab-context&quot;\"><\/div><\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div  class=\"ms-slide\" data-delay=\"3\" data-fill-mode=\"fill\"  >\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/sporchernest-hotel.de\/wp-content\/plugins\/master-slider\/public\/assets\/css\/blank.gif\" alt=\"\" title=\"\" data-src=\"https:\/\/sporchernest-hotel.de\/wp-content\/uploads\/2019\/01\/Zimmer-17.jpg\" \/>\n\n\n\t<img decoding=\"async\" class=\"ms-thumb\" src=\"https:\/\/sporchernest-hotel.de\/wp-content\/uploads\/2019\/01\/Zimmer-17-128x95.jpg\" alt=\"\" \/>\n\t<div class=\"ms-thumb\" ><div class=\"ms-tab-context\"><div class=\"&quot;ms-tab-context&quot;\"><\/div><\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div  class=\"ms-slide\" data-delay=\"3\" data-fill-mode=\"fill\"  >\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/sporchernest-hotel.de\/wp-content\/plugins\/master-slider\/public\/assets\/css\/blank.gif\" alt=\"\" title=\"\" data-src=\"https:\/\/sporchernest-hotel.de\/wp-content\/uploads\/2019\/01\/Zimmer-28.jpg\" \/>\n\n\n\t<img decoding=\"async\" class=\"ms-thumb\" src=\"https:\/\/sporchernest-hotel.de\/wp-content\/uploads\/2019\/01\/Zimmer-28-128x95.jpg\" alt=\"\" \/>\n\t<div class=\"ms-thumb\" ><div class=\"ms-tab-context\"><div class=\"&quot;ms-tab-context&quot;\"><\/div><\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div  class=\"ms-slide\" data-delay=\"3\" data-fill-mode=\"fill\"  >\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/sporchernest-hotel.de\/wp-content\/plugins\/master-slider\/public\/assets\/css\/blank.gif\" alt=\"\" title=\"\" data-src=\"https:\/\/sporchernest-hotel.de\/wp-content\/uploads\/2019\/01\/Zimmer-30.jpg\" \/>\n\n\n\t<img decoding=\"async\" class=\"ms-thumb\" src=\"https:\/\/sporchernest-hotel.de\/wp-content\/uploads\/2019\/01\/Zimmer-30-128x95.jpg\" alt=\"\" \/>\n\t<div class=\"ms-thumb\" ><div class=\"ms-tab-context\"><div class=\"&quot;ms-tab-context&quot;\"><\/div><\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div  class=\"ms-slide\" data-delay=\"3\" data-fill-mode=\"fill\"  >\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/sporchernest-hotel.de\/wp-content\/plugins\/master-slider\/public\/assets\/css\/blank.gif\" alt=\"\" title=\"\" data-src=\"https:\/\/sporchernest-hotel.de\/wp-content\/uploads\/2019\/01\/Zimmer-31.jpg\" \/>\n\n\n\t<img decoding=\"async\" class=\"ms-thumb\" src=\"https:\/\/sporchernest-hotel.de\/wp-content\/uploads\/2019\/01\/Zimmer-31-128x95.jpg\" alt=\"\" \/>\n\t<div class=\"ms-thumb\" ><div class=\"ms-tab-context\"><div class=\"&quot;ms-tab-context&quot;\"><\/div><\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div  class=\"ms-slide\" data-delay=\"3\" data-fill-mode=\"fill\"  >\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/sporchernest-hotel.de\/wp-content\/plugins\/master-slider\/public\/assets\/css\/blank.gif\" alt=\"\" title=\"\" data-src=\"https:\/\/sporchernest-hotel.de\/wp-content\/uploads\/2019\/01\/Zimmer-32.jpg\" \/>\n\n\n\t<img decoding=\"async\" class=\"ms-thumb\" src=\"https:\/\/sporchernest-hotel.de\/wp-content\/uploads\/2019\/01\/Zimmer-32-128x95.jpg\" alt=\"\" \/>\n\t<div class=\"ms-thumb\" ><div class=\"ms-tab-context\"><div class=\"&quot;ms-tab-context&quot;\"><\/div><\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div  class=\"ms-slide\" data-delay=\"3\" data-fill-mode=\"fill\"  >\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/sporchernest-hotel.de\/wp-content\/plugins\/master-slider\/public\/assets\/css\/blank.gif\" alt=\"\" title=\"\" data-src=\"https:\/\/sporchernest-hotel.de\/wp-content\/uploads\/2019\/01\/Zimmer-33.jpg\" \/>\n\n\n\t<img decoding=\"async\" class=\"ms-thumb\" src=\"https:\/\/sporchernest-hotel.de\/wp-content\/uploads\/2019\/01\/Zimmer-33-128x95.jpg\" alt=\"\" \/>\n\t<div class=\"ms-thumb\" ><div class=\"ms-tab-context\"><div class=\"&quot;ms-tab-context&quot;\"><\/div><\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div  class=\"ms-slide\" data-delay=\"3\" data-fill-mode=\"fill\"  >\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/sporchernest-hotel.de\/wp-content\/plugins\/master-slider\/public\/assets\/css\/blank.gif\" alt=\"\" title=\"\" data-src=\"https:\/\/sporchernest-hotel.de\/wp-content\/uploads\/2019\/01\/Dusche-Balkenzimmer.jpg\" \/>\n\n\n\t<img decoding=\"async\" class=\"ms-thumb\" src=\"https:\/\/sporchernest-hotel.de\/wp-content\/uploads\/2019\/01\/Dusche-Balkenzimmer-128x95.jpg\" alt=\"\" \/>\n\t<div class=\"ms-thumb\" ><div class=\"ms-tab-context\"><div class=\"&quot;ms-tab-context&quot;\"><\/div><\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div  class=\"ms-slide\" data-delay=\"3\" data-fill-mode=\"fill\"  >\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/sporchernest-hotel.de\/wp-content\/plugins\/master-slider\/public\/assets\/css\/blank.gif\" alt=\"\" title=\"\" data-src=\"https:\/\/sporchernest-hotel.de\/wp-content\/uploads\/2019\/01\/Zimmer-35.jpg\" \/>\n\n\n\t<img decoding=\"async\" class=\"ms-thumb\" src=\"https:\/\/sporchernest-hotel.de\/wp-content\/uploads\/2019\/01\/Zimmer-35-128x95.jpg\" alt=\"\" \/>\n\t<div class=\"ms-thumb\" ><div class=\"ms-tab-context\"><div class=\"&quot;ms-tab-context&quot;\"><\/div><\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div  class=\"ms-slide\" data-delay=\"3\" data-fill-mode=\"fill\"  >\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/sporchernest-hotel.de\/wp-content\/plugins\/master-slider\/public\/assets\/css\/blank.gif\" alt=\"\" title=\"\" data-src=\"https:\/\/sporchernest-hotel.de\/wp-content\/uploads\/2019\/01\/Zimmer-37.jpg\" \/>\n\n\n\t<img decoding=\"async\" class=\"ms-thumb\" src=\"https:\/\/sporchernest-hotel.de\/wp-content\/uploads\/2019\/01\/Zimmer-37-128x95.jpg\" alt=\"\" \/>\n\t<div class=\"ms-thumb\" ><div class=\"ms-tab-context\"><div class=\"&quot;ms-tab-context&quot;\"><\/div><\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div  class=\"ms-slide\" data-delay=\"3\" data-fill-mode=\"fill\"  >\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/sporchernest-hotel.de\/wp-content\/plugins\/master-slider\/public\/assets\/css\/blank.gif\" alt=\"\" title=\"\" data-src=\"https:\/\/sporchernest-hotel.de\/wp-content\/uploads\/2019\/01\/Cafe1.jpg\" \/>\n\n\n\t<img decoding=\"async\" class=\"ms-thumb\" src=\"https:\/\/sporchernest-hotel.de\/wp-content\/uploads\/2019\/01\/Cafe1-128x95.jpg\" alt=\"\" \/>\n\t<div class=\"ms-thumb\" ><div class=\"ms-tab-context\"><div class=\"&quot;ms-tab-context&quot;\"><\/div><\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div  class=\"ms-slide\" data-delay=\"3\" data-fill-mode=\"fill\"  >\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/sporchernest-hotel.de\/wp-content\/plugins\/master-slider\/public\/assets\/css\/blank.gif\" alt=\"\" title=\"\" data-src=\"https:\/\/sporchernest-hotel.de\/wp-content\/uploads\/2019\/01\/Cafe2.jpg\" \/>\n\n\n\t<img decoding=\"async\" class=\"ms-thumb\" src=\"https:\/\/sporchernest-hotel.de\/wp-content\/uploads\/2019\/01\/Cafe2-128x95.jpg\" alt=\"\" \/>\n\t<div class=\"ms-thumb\" ><div class=\"ms-tab-context\"><div class=\"&quot;ms-tab-context&quot;\"><\/div><\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div  class=\"ms-slide\" data-delay=\"3\" data-fill-mode=\"fill\"  >\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/sporchernest-hotel.de\/wp-content\/plugins\/master-slider\/public\/assets\/css\/blank.gif\" alt=\"\" title=\"\" data-src=\"https:\/\/sporchernest-hotel.de\/wp-content\/uploads\/2019\/02\/cafeauslaufgalerie.jpg\" \/>\n\n\n\t<img decoding=\"async\" class=\"ms-thumb\" src=\"https:\/\/sporchernest-hotel.de\/wp-content\/uploads\/2019\/02\/cafeauslaufgalerie-128x95.jpg\" alt=\"\" \/>\n\t<div class=\"ms-thumb\" ><div class=\"ms-tab-context\"><div class=\"&quot;ms-tab-context&quot;\"><\/div><\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div  class=\"ms-slide\" data-delay=\"3\" data-fill-mode=\"fill\"  >\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/sporchernest-hotel.de\/wp-content\/plugins\/master-slider\/public\/assets\/css\/blank.gif\" alt=\"\" title=\"\" data-src=\"https:\/\/sporchernest-hotel.de\/wp-content\/uploads\/2019\/01\/Cafe3.jpg\" \/>\n\n\n\t<img decoding=\"async\" class=\"ms-thumb\" src=\"https:\/\/sporchernest-hotel.de\/wp-content\/uploads\/2019\/01\/Cafe3-128x95.jpg\" alt=\"\" \/>\n\t<div class=\"ms-thumb\" ><div class=\"ms-tab-context\"><div class=\"&quot;ms-tab-context&quot;\"><\/div><\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div  class=\"ms-slide\" data-delay=\"3\" data-fill-mode=\"fill\"  >\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/sporchernest-hotel.de\/wp-content\/plugins\/master-slider\/public\/assets\/css\/blank.gif\" alt=\"\" title=\"\" data-src=\"https:\/\/sporchernest-hotel.de\/wp-content\/uploads\/2020\/06\/HOT_07-2020.jpg\" \/>\n\n\n\t<img decoding=\"async\" class=\"ms-thumb\" src=\"https:\/\/sporchernest-hotel.de\/wp-content\/uploads\/2020\/06\/HOT_07-2020-128x95.jpg\" alt=\"\" \/>\n\t<div class=\"ms-thumb\" ><div class=\"ms-tab-context\"><div class=\"&quot;ms-tab-context&quot;\"><\/div><\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div  class=\"ms-slide\" data-delay=\"3\" data-fill-mode=\"fill\"  >\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/sporchernest-hotel.de\/wp-content\/plugins\/master-slider\/public\/assets\/css\/blank.gif\" alt=\"\" title=\"\" data-src=\"https:\/\/sporchernest-hotel.de\/wp-content\/uploads\/2020\/06\/HOT_08-2020.jpg\" \/>\n\n\n\t<img decoding=\"async\" class=\"ms-thumb\" src=\"https:\/\/sporchernest-hotel.de\/wp-content\/uploads\/2020\/06\/HOT_08-2020-128x95.jpg\" alt=\"\" \/>\n\t<div class=\"ms-thumb\" ><div class=\"ms-tab-context\"><div class=\"&quot;ms-tab-context&quot;\"><\/div><\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div  class=\"ms-slide\" data-delay=\"3\" data-fill-mode=\"fill\"  >\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/sporchernest-hotel.de\/wp-content\/plugins\/master-slider\/public\/assets\/css\/blank.gif\" alt=\"\" title=\"\" data-src=\"https:\/\/sporchernest-hotel.de\/wp-content\/uploads\/2019\/01\/Cafe6.jpg\" \/>\n\n\n\t<img decoding=\"async\" class=\"ms-thumb\" src=\"https:\/\/sporchernest-hotel.de\/wp-content\/uploads\/2019\/01\/Cafe6-128x95.jpg\" alt=\"\" \/>\n\t<div class=\"ms-thumb\" ><div class=\"ms-tab-context\"><div class=\"&quot;ms-tab-context&quot;\"><\/div><\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div  class=\"ms-slide\" data-delay=\"3\" data-fill-mode=\"fill\"  >\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/sporchernest-hotel.de\/wp-content\/plugins\/master-slider\/public\/assets\/css\/blank.gif\" alt=\"\" title=\"\" data-src=\"https:\/\/sporchernest-hotel.de\/wp-content\/uploads\/2019\/01\/Cafe7.jpg\" \/>\n\n\n\t<img decoding=\"async\" class=\"ms-thumb\" src=\"https:\/\/sporchernest-hotel.de\/wp-content\/uploads\/2019\/01\/Cafe7-128x95.jpg\" alt=\"\" \/>\n\t<div class=\"ms-thumb\" ><div class=\"ms-tab-context\"><div class=\"&quot;ms-tab-context&quot;\"><\/div><\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div  class=\"ms-slide\" data-delay=\"3\" data-fill-mode=\"fill\"  >\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/sporchernest-hotel.de\/wp-content\/plugins\/master-slider\/public\/assets\/css\/blank.gif\" alt=\"\" title=\"\" data-src=\"https:\/\/sporchernest-hotel.de\/wp-content\/uploads\/2019\/01\/Cafe8.jpg\" \/>\n\n\n\t<img decoding=\"async\" class=\"ms-thumb\" src=\"https:\/\/sporchernest-hotel.de\/wp-content\/uploads\/2019\/01\/Cafe8-128x95.jpg\" alt=\"\" \/>\n\t<div class=\"ms-thumb\" ><div class=\"ms-tab-context\"><div class=\"&quot;ms-tab-context&quot;\"><\/div><\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div  class=\"ms-slide\" data-delay=\"3\" data-fill-mode=\"fill\"  >\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/sporchernest-hotel.de\/wp-content\/plugins\/master-slider\/public\/assets\/css\/blank.gif\" alt=\"\" title=\"\" data-src=\"https:\/\/sporchernest-hotel.de\/wp-content\/uploads\/2019\/01\/Cafe9-neu.jpg\" \/>\n\n\n\t<img decoding=\"async\" class=\"ms-thumb\" src=\"https:\/\/sporchernest-hotel.de\/wp-content\/uploads\/2019\/01\/Cafe9-neu-128x95.jpg\" alt=\"\" \/>\n\t<div class=\"ms-thumb\" ><div class=\"ms-tab-context\"><div class=\"&quot;ms-tab-context&quot;\"><\/div><\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div  class=\"ms-slide\" data-delay=\"3\" data-fill-mode=\"fill\"  >\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/sporchernest-hotel.de\/wp-content\/plugins\/master-slider\/public\/assets\/css\/blank.gif\" alt=\"\" title=\"\" data-src=\"https:\/\/sporchernest-hotel.de\/wp-content\/uploads\/2019\/01\/Cafe10.jpg\" \/>\n\n\n\t<img decoding=\"async\" class=\"ms-thumb\" src=\"https:\/\/sporchernest-hotel.de\/wp-content\/uploads\/2019\/01\/Cafe10-128x95.jpg\" alt=\"\" \/>\n\t<div class=\"ms-thumb\" ><div class=\"ms-tab-context\"><div class=\"&quot;ms-tab-context&quot;\"><\/div><\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div  class=\"ms-slide\" data-delay=\"3\" data-fill-mode=\"fill\"  >\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/sporchernest-hotel.de\/wp-content\/plugins\/master-slider\/public\/assets\/css\/blank.gif\" alt=\"\" title=\"\" data-src=\"https:\/\/sporchernest-hotel.de\/wp-content\/uploads\/2019\/01\/Cafe11.jpg\" \/>\n\n\n\t<img decoding=\"async\" class=\"ms-thumb\" src=\"https:\/\/sporchernest-hotel.de\/wp-content\/uploads\/2019\/01\/Cafe11-128x95.jpg\" alt=\"\" \/>\n\t<div class=\"ms-thumb\" ><div class=\"ms-tab-context\"><div class=\"&quot;ms-tab-context&quot;\"><\/div><\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div  class=\"ms-slide\" data-delay=\"3\" data-fill-mode=\"fill\"  >\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/sporchernest-hotel.de\/wp-content\/plugins\/master-slider\/public\/assets\/css\/blank.gif\" alt=\"\" title=\"\" data-src=\"https:\/\/sporchernest-hotel.de\/wp-content\/uploads\/2019\/01\/Cafe12.jpg\" \/>\n\n\n\t<img decoding=\"async\" class=\"ms-thumb\" src=\"https:\/\/sporchernest-hotel.de\/wp-content\/uploads\/2019\/01\/Cafe12-128x95.jpg\" alt=\"\" \/>\n\t<div class=\"ms-thumb\" ><div class=\"ms-tab-context\"><div class=\"&quot;ms-tab-context&quot;\"><\/div><\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div  class=\"ms-slide\" data-delay=\"3\" data-fill-mode=\"fill\"  >\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/sporchernest-hotel.de\/wp-content\/plugins\/master-slider\/public\/assets\/css\/blank.gif\" alt=\"\" title=\"\" data-src=\"https:\/\/sporchernest-hotel.de\/wp-content\/uploads\/2019\/03\/T_Raum-8-960.jpg\" \/>\n\n\n\t<img decoding=\"async\" class=\"ms-thumb\" src=\"https:\/\/sporchernest-hotel.de\/wp-content\/uploads\/2019\/03\/T_Raum-8-960-128x95.jpg\" alt=\"\" \/>\n\t<div class=\"ms-thumb\" ><div class=\"ms-tab-context\"><div class=\"&quot;ms-tab-context&quot;\"><\/div><\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div  class=\"ms-slide\" data-delay=\"3\" data-fill-mode=\"fill\"  >\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/sporchernest-hotel.de\/wp-content\/plugins\/master-slider\/public\/assets\/css\/blank.gif\" alt=\"\" title=\"\" data-src=\"https:\/\/sporchernest-hotel.de\/wp-content\/uploads\/2019\/03\/T_Raum-1-960.jpg\" \/>\n\n\n\t<img decoding=\"async\" class=\"ms-thumb\" src=\"https:\/\/sporchernest-hotel.de\/wp-content\/uploads\/2019\/03\/T_Raum-1-960-128x95.jpg\" alt=\"\" \/>\n\t<div class=\"ms-thumb\" ><div class=\"ms-tab-context\"><div class=\"&quot;ms-tab-context&quot;\"><\/div><\/div>\n<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t<\/div>\n\t\t\t<!-- END MasterSlider Main -->\n\n\t\t\t \n\t\t<\/div>\n\t\t<!-- END MasterSlider -->\n\n\t\t<script>\n\t\t(function ( $ ) {\n\t\t\t\"use strict\";\n\n\t\t\t$(function () {\n\t\t\t\tvar masterslider_18c6 = new MasterSlider();\n\n\t\t\t\t\/\/ slider controls\n\t\t\t\tmasterslider_18c6.control('arrows'     ,{ autohide:true, overVideo:true  });\t\t\t\tmasterslider_18c6.control('bullets'    ,{ autohide:true, overVideo:true, dir:'h', align:'bottom' , margin:-40  });\n\n\t\t\t\tmasterslider_18c6.control('thumblist'  ,{ autohide:false, overVideo:true, dir:'v', speed:17, inset:false, arrows:false, hover:false, customClass:'', align:'right',type:'thumbs', margin:25, width:128, height:95, space:11, fillMode:'fill'  });\n\t\t\t\t\/\/ slider setup\n\t\t\t\tmasterslider_18c6.setup(\"MS6a97e938c18c6\", {\n\t\t\t\t\t\twidth           : 960,\n\t\t\t\t\t\theight          : 638,\n\t\t\t\t\t\tminHeight       : 0,\n\t\t\t\t\t\tspace           : 0,\n\t\t\t\t\t\tstart           : 1,\n\t\t\t\t\t\tgrabCursor      : true,\n\t\t\t\t\t\tswipe           : true,\n\t\t\t\t\t\tmouse           : true,\n\t\t\t\t\t\tlayout          : \"boxed\",\n\t\t\t\t\t\twheel           : false,\n\t\t\t\t\t\tautoplay        : false,\n\t\t\t\t\t\tinstantStartLayers:false,\n\t\t\t\t\t\tloop            : false,\n\t\t\t\t\t\tshuffle         : false,\n\t\t\t\t\t\tpreload         : 0,\n\t\t\t\t\t\theightLimit     : true,\n\t\t\t\t\t\tautoHeight      : false,\n\t\t\t\t\t\tsmoothHeight    : true,\n\t\t\t\t\t\tendPause        : false,\n\t\t\t\t\t\toverPause       : true,\n\t\t\t\t\t\tfillMode        : \"fill\",\n\t\t\t\t\t\tcenterControls  : true,\n\t\t\t\t\t\tstartOnAppear   : false,\n\t\t\t\t\t\tlayersMode      : \"center\",\n\t\t\t\t\t\thideLayers      : false,\n\t\t\t\t\t\tfullscreenMargin: 0,\n\t\t\t\t\t\tspeed           : 20,\n\t\t\t\t\t\tdir             : \"h\",\n\t\t\t\t\t\tparallaxMode    : 'swipe',\n\t\t\t\t\t\tview            : \"basic\"\n\t\t\t\t});\n\n\t\t\t\t\n\t\t\t\twindow.masterslider_instances = window.masterslider_instances || [];\n\t\t\t\twindow.masterslider_instances.push( masterslider_18c6 );\n\t\t\t });\n\n\t\t})(jQuery);\n\t\t<\/script>\n\n\n&nbsp;<br \/>\n&nbsp;","protected":false},"excerpt":{"rendered":"<p>Galerie &nbsp; Ein kleiner Rundgang durchs Sporcher Nest&#8230; &nbsp; &nbsp; &nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template-full-width.php","meta":{"footnotes":""},"class_list":["post-13","page","type-page","status-publish","hentry"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/sporchernest-hotel.de\/de\/wp-json\/wp\/v2\/pages\/13","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sporchernest-hotel.de\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/sporchernest-hotel.de\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/sporchernest-hotel.de\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sporchernest-hotel.de\/de\/wp-json\/wp\/v2\/comments?post=13"}],"version-history":[{"count":13,"href":"https:\/\/sporchernest-hotel.de\/de\/wp-json\/wp\/v2\/pages\/13\/revisions"}],"predecessor-version":[{"id":259,"href":"https:\/\/sporchernest-hotel.de\/de\/wp-json\/wp\/v2\/pages\/13\/revisions\/259"}],"wp:attachment":[{"href":"https:\/\/sporchernest-hotel.de\/de\/wp-json\/wp\/v2\/media?parent=13"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}